{"id":235,"count":1,"description":"","link":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/","name":"Music Hubs","slug":"music-hubs","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Music Hubs Archives - Matthew Rusk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Music Hubs Archives - Matthew Rusk\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/\" \/>\n<meta property=\"og:site_name\" content=\"Matthew Rusk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/\",\"url\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/\",\"name\":\"Music Hubs Archives - Matthew Rusk\",\"isPartOf\":{\"@id\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Music Hubs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/#website\",\"url\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/\",\"name\":\"Matthew Rusk\",\"description\":\"Student Entrepreneur in Residence\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sites.exeter.ac.uk\/matthewrusk\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Music Hubs Archives - Matthew Rusk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/","og_locale":"en_US","og_type":"article","og_title":"Music Hubs Archives - Matthew Rusk","og_url":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/","og_site_name":"Matthew Rusk","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/","url":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/","name":"Music Hubs Archives - Matthew Rusk","isPartOf":{"@id":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/#website"},"breadcrumb":{"@id":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/tag\/music-hubs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/"},{"@type":"ListItem","position":2,"name":"Music Hubs"}]},{"@type":"WebSite","@id":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/#website","url":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/","name":"Matthew Rusk","description":"Student Entrepreneur in Residence","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/wp-json\/wp\/v2\/tags\/235"}],"collection":[{"href":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sites.exeter.ac.uk\/matthewrusk\/wp-json\/wp\/v2\/posts?tags=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}